{"id":1279,"date":"2023-04-01T13:47:54","date_gmt":"2023-04-01T13:47:54","guid":{"rendered":"https:\/\/www.andesport.com\/?p=1279"},"modified":"2024-06-04T17:55:32","modified_gmt":"2024-06-04T20:55:32","slug":"aconcagua-climb-entrainement-de-base","status":"publish","type":"post","link":"https:\/\/andesport.net\/fr\/aconcagua-climb-entrainement-de-base\/","title":{"rendered":"ACONCAGUA CLIMB: ENTRA\u00ceNEMENT DE BASE"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\" id=\"h-aconcagua-climb-entrainement-de-base\">ACONCAGUA CLIMB: ENTRA\u00ceNEMENT DE BASE<\/h1>\n\n\n\n<p>Escalader l\u2019Aconcagua est, entre autres, une grande satisfaction personnelle et d\u2019\u00e9quipe. Il est certain que si vous voulez profiter de l\u2019exp\u00e9rience de l\u2019alpinisme, tout d\u00e9pend de votre entra\u00eenement pr\u00e9c\u00e9dent. Les chances de succ\u00e8s peuvent \u00eatre grandement am\u00e9lior\u00e9es, ainsi que votre marge de s\u00e9curit\u00e9, afin d\u2019\u00e9viter les maladies et les accidents en montagne. Par cons\u00e9quent, il est important de garder \u00e0 l\u2019esprit qu\u2019une pr\u00e9paration et une acclimatation ad\u00e9quates pour grimper \u00e0 l\u2019Aconcagua sont indispensables pour disposer de la force n\u00e9cessaire pour \u00e9viter l\u2019\u00e9puisement au cours du voyage.<\/p>\n\n\n\n<p>Pour \u00eatre honor\u00e9 lors de l\u2019ascension, il est essentiel de suivre un entra\u00eenement pr\u00e9alable en escaladant des montagnes de diff\u00e9rentes tailles et en augmentant lentement l\u2019altitude. Vous devrez d\u00e9velopper un haut degr\u00e9 de r\u00e9sistance \u00e0 l\u2019endurance, une tol\u00e9rance \u00e0 l\u2019altitude \u00e9lev\u00e9e et un fort conditionnement cardiovasculaire. Ce n\u2019est pas parce que vous faites de l\u2019exercice physique r\u00e9gulier (quatre \u00e0 six fois par semaine) que vous disposez de la climatisation n\u00e9cessaire pour atteindre le point culminant de l\u2019Am\u00e9rique du Sud. Beaucoup de personnes qui ont l\u2019endurance de courir au marathon ou de participer \u00e0 des triathlons ne parviennent pas \u00e0 atteindre les sommets de haute altitude. Une bonne forme cardiovasculaire ne suffit tout simplement pas. Concentrez-vous sur la mise en forme de la condition physique n\u00e9cessaire pour gravir des \u00e9l\u00e9vations verticales de 3 500 pieds au cours des journ\u00e9es successives, avec une charge de 45 \u00e0 50 livres.<\/p>\n\n\n\n<p>Donnez la priorit\u00e9 \u00e0 vos efforts d\u2019entra\u00eenement de la mani\u00e8re suivante, en supposant que vous soyez en bonne sant\u00e9 et sans blessure:<\/p>\n\n\n\n<p><strong>1.&nbsp;<\/strong>Conditionnement d\u2019escalade: randonn\u00e9es, marches et mont\u00e9es d\u2019escalades bond\u00e9es<br><strong>2.&nbsp;<\/strong>La musculation du bas du corps et du tronc<br><strong>3.&nbsp;<\/strong>Entra\u00eenement cardiovasculaire, comprenant des entra\u00eenements a\u00e9robies et ana\u00e9robies sans poids<br><strong>4.&nbsp;<\/strong>Formation \u00e0 la flexibilit\u00e9<br><strong>5.&nbsp;<\/strong>Conditionnement psychologique<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conditionnement-d-escalade\">Conditionnement d\u2019escalade<\/h2>\n\n\n\n<p>1. Entra\u00eenez-vous \u00e0 d\u00e9velopper votre \u00e9nergie avec des activit\u00e9s telles que la course \u00e0 pied, le v\u00e9lo, le ciel ou la marche rapide. Faites tourner les routines pour \u00e9viter les blessures dues \u00e0 un exc\u00e8s d\u2019exercice. La natation est \u00e9galement une excellente forme d\u2019entra\u00eenement car elle n\u2019impose pas de stress aux articulations. Utilisez n\u2019importe quel terrain de surface vari\u00e9 (par exemple, des lits de gravier, des dunes de sable, des berges de rivi\u00e8res) auquel vous avez acc\u00e8s. Si vous vivez dans un endroit relativement plat, montez et descendez les escaliers ou entra\u00eenez-vous sur un tapis roulant ou un ma\u00eetre d\u2019escalier inclin\u00e9.<\/p>\n\n\n\n<p>2. L\u2019entra\u00eenement progressif avec poids procure de la r\u00e9sistance. Augmentez votre poids progressivement jusqu\u2019\u00e0 ce que vous vous sentiez \u00e0 l\u2019aise avec le sac de 50 livres. Il am\u00e9liore le m\u00e9tabolisme ana\u00e9robie: le processus principal qui nourrit le travail des muscles, qui est aliment\u00e9 par les glucides stock\u00e9s dans notre corps, de sorte qu\u2019ils n\u2019ont pas besoin de m\u00e9taboliser l\u2019oxyg\u00e8ne suppl\u00e9mentaire. Ne courez pas avec du poids.<\/p>\n\n\n\n<p>3. Entra\u00eenez-vous autant que possible, escaladez des montagnes, passez toute la journ\u00e9e ou plus en excursion. Pour \u00eatre un bon grimpeur, pour pouvoir gravir de hautes montagnes, il faut s\u2019entra\u00eener. Vous commencez avec de petites montagnes et un sac \u00e0 dos moyen et augmentez les deux progressivement.<\/p>\n\n\n\n<p>En d\u00e9but de saison, commencez par une randonn\u00e9e qui permet de gagner jusqu\u2019\u00e0 2000 fois la distance parcourue sur une distance de 5 \u00e0 7 miles (4,85 km) et de porter jusqu\u2019\u00e0 20 livres. essayez d\u2019ajouter 3 \u00e0 5 kilos jusqu\u2019\u00e0 ce que vous soyez \u00e0 l\u2019aise avec un sac de 50 kilos, puis augmentez le gain d\u2019altitude total et le kilom\u00e9trage parcouru. Lorsque vous pouvez gagner 3 000 pieds tout en portant un sac de 50 kilos, commencez \u00e0 diminuer les pauses et \u00e0 augmenter la vitesse \u00e0 chaque s\u00e9ance de conditionnement. Un mois apr\u00e8s votre ascension, vous devriez \u00eatre \u00e0 l\u2019aise pour faire de la randonn\u00e9e plusieurs jours \u00e0 la suite, avec au moins 20 kg.<\/p>\n\n\n\n<p>Astuce: lorsque vous portez un sac \u00e0 dos lors d\u2019une descente, d\u2019une marche ou d\u2019une descente, essayez d\u2019en porter un peu moins dans votre sac \u00e0 dos afin de vous prot\u00e9ger les genoux. De nombreux formateurs conseillent de porter des bouteilles d\u2019eau sur la colline, puis de les vider en haut afin d\u2019all\u00e9ger votre sac \u00e0 dos pour le voyage.<\/p>\n\n\n\n<p>Deux techniques d\u2019entra\u00eenement utiles pour le trekking en haute altitude sont:<\/p>\n\n\n\n<p><strong>1) Entra\u00eenement par intervalles:&nbsp;<\/strong>pour inclure l\u2019entra\u00eenement par intervalles, recherchez une colline ou des escaliers raides qui vous permettront de monter r\u00e9guli\u00e8rement pendant plusieurs minutes. Poussez aussi fort que vous pouvez monter, puis r\u00e9cup\u00e9rez en descendant, et r\u00e9p\u00e9tez-le pour une dur\u00e9e allant de 20 \u00e0 45 minutes en fonction de votre proximit\u00e9. Ajoutez progressivement du poids \u00e0 votre sac (pas plus de 10% par semaine) jusqu\u2019\u00e0 ce que vous puissiez porter 40 kilos tout le temps. Si possible, participez \u00e0 autant de randonn\u00e9es en altitude \u2013 et dans des conditions hivernales \u2013 que vous pourrez probablement apprendre comment votre corps r\u00e9agit par temps extr\u00eamement froid et \u00e0 plus de 13 000 pieds d\u2019altitude.<\/p>\n\n\n\n<p><strong>2) Entra\u00eenement dos \u00e0 dos:&nbsp;<\/strong>il s\u2019agit d\u2019une randonn\u00e9e avec votre poids cible (50 livres) le premier jour pour un gain d\u2019au moins 3 000 pieds, et un sac un peu plus l\u00e9ger (30 \u00e0 35 livres) pour augmentation du kilom\u00e9trage ou de l\u2019altitude le deuxi\u00e8me jour pour simuler les exigences cons\u00e9cutives des longues journ\u00e9es de votre voyage. Ce sera non seulement physiquement, mais aussi pr\u00e9parera psychologiquement au d\u00e9fi de r\u00e9p\u00e9ter des journ\u00e9es d\u2019effort intense sans jours de r\u00e9cup\u00e9ration entre les deux.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conditionnement-en-force\">Conditionnement en force<\/h2>\n\n\n\n<p>L\u2019entra\u00eenement avec des poids libres, des bagues, des sacs \u00e0 dos, des exercices de musculation ou des appareils de sport vous aidera. Vous renforcez votre r\u00e9sistance g\u00e9n\u00e9rale, en particulier au niveau du noyau (bas du dos et des abdominaux), du haut du dos, des \u00e9paules et des jambes.<br>L\u2019utilisation \u00e0 la fois d\u2019\u00e9quipement de gymnastique et de grands espaces naturels fournira un programme d\u2019exercice plus \u00e9quilibr\u00e9. Vous devriez essayer de faire au moins la moiti\u00e9 de vos s\u00e9ances d\u2019entra\u00eenement \u00e0 l\u2019ext\u00e9rieur. Cela pourrait inclure la marche et la course (dans les escaliers et les collines \u00e9galement) et le cyclisme. La marche et l\u2019escalade avec un sac de pes\u00e9e est essentielle. Si vous n\u2019avez pas de collines, pourquoi ne pas opter pour les escaliers, les gradins, les stades et m\u00eame les escaliers des immeubles de grande hauteur? N\u2019oubliez pas de passer du temps \u00e0 travailler sur les muscles des jambes, du dos et des \u00e9paules et souvenez-vous que votre propre poids corporel peut \u00eatre aussi efficace que des poids ou des machines.<\/p>\n\n\n\n<p>D\u00e9velopper la force dans le haut du dos et les \u00e9paules vous aidera dans des t\u00e2ches telles que porter votre sac \u00e0 dos et utiliser efficacement les b\u00e2tons de randonn\u00e9e. Les mollets, les hanches, les quads, les ischio-jambiers et les fessiers participent tous \u00e0 la mont\u00e9e et \u00e0 la descente de pentes raides et raides enneig\u00e9es et glac\u00e9es, et une grande endurance est requise dans toutes les zones des jambes et des hanches.<\/p>\n\n\n\n<p>Lorsque vous d\u00e9marrez un programme de conditionnement physique, concentrez-vous sur des exercices compos\u00e9s tels que les squats, les fentes, les augmentations progressives, les plong\u00e9es, les tractions, les rang\u00e9es, les soulev\u00e9s de terre, les presses \u00e0 colonne, les pompes et les presses suspendues.<\/p>\n\n\n\n<p>Au d\u00e9but de la phase de conditionnement physique, concentrez-vous sur la mise en place de bases d\u2019entra\u00eenement plus difficiles. En continuant de vous entra\u00eener, vous vous concentrez sur le renforcement de votre force. Quatre \u00e0 six semaines avant votre ascension, modifiez votre entra\u00eenement pour vous concentrer sur l\u2019endurance de la force afin de transformer la force nouvellement acquise en une plus grande endurance de force. Chaque phase d\u2019entra\u00eenement doit varier en fonction du poids, des r\u00e9p\u00e9titions effectu\u00e9es, du nombre de s\u00e9ries et des intervalles de repos. Quelle que soit la phase d\u2019entra\u00eenement, veillez toujours \u00e0 conserver une forme correcte pour \u00e9viter toute blessure ou effort.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conditionnement-cardiovasculaire\">Conditionnement cardiovasculaire<\/h2>\n\n\n\n<p>Lorsque vous d\u00e9butez votre programme d\u2019entra\u00eenement cardiovasculaire, commencez avec trois s\u00e9ances d\u2019entra\u00eenement hebdomadaires de 30 \u00e0 45 minutes d\u2019activit\u00e9 soutenue \u00e0 une intensit\u00e9 mod\u00e9r\u00e9e, puis d\u00e9veloppez 4 \u00e0 5 s\u00e9ances d\u2019a\u00e9robic ou faites de l\u2019effort pendant au moins 45 \u00e0 60 minutes. Veillez \u00e0 pr\u00e9voir un \u00e9chauffement doux de 5 \u00e0 10 minutes avant de travailler \u00e0 votre rythme cardiaque cible pour la journ\u00e9e (pour la plupart des s\u00e9ances d\u2019entra\u00eenement, choisissez un niveau d\u2019effort qui vous permet de relier quelques mots dans une phrase, mais en laissant le sentiment confortablement fatigu\u00e9e \u00e0 la fin de la s\u00e9ance d\u2019entra\u00eenement) et d\u00e9tendez-vous avec 5 \u00e0 10 minutes d\u2019\u00e9tirement appropri\u00e9 des muscles que vous utilisez le plus dans votre activit\u00e9, y compris le bas du dos, les mollets, les cuisses, les hanches et les quadriceps.<br>Bien que le cyclisme, l\u2019aviron et la natation soient des options a\u00e9robiques pour les premiers stades de l\u2019entra\u00eenement, assurez-vous, au fur et \u00e0 mesure que vous vous rapprochez de votre voyage, que des activit\u00e9s d\u2019entra\u00eenement a\u00e9robique chargent le dos et les jambes de la m\u00eame mani\u00e8re que la randonn\u00e9e. Les options appropri\u00e9es incluent la course en sentier, la marche en escalier ou la marche en escalier, le jogging ou la mont\u00e9e et la descente de collines.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conditionnement-de-flexibilite\">Conditionnement de flexibilit\u00e9<\/h2>\n\n\n\n<p>Veillez \u00e0 inclure au moins 5 \u00e0 10 minutes d\u2019\u00e9tirement cibl\u00e9 apr\u00e8s chaque entra\u00eenement, en particulier pour les ischio-jambiers, les fessiers, les hanches, les mollets, les avant-bras, le bas du dos et les quadriceps. Si vous avez des pr\u00e9occupations en d\u00e9but de saison, veillez \u00e0 avoir une amplitude de mouvement normale autour de toutes vos articulations. Cela deviendra encore plus important si vous ajoutez du poids et de la distance \u00e0 vos climatiseurs.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conditionnement-psychologique\">Conditionnement psychologique<\/h2>\n\n\n\n<p>\u00catre mentalement apte \u00e0 l\u2019exp\u00e9dition. Avant de commencer, il est n\u00e9cessaire de comprendre que souvent vous allez vous sentir mal \u00e0 l\u2019aise, peut-\u00eatre que vous allez passer quelques jours dans une tente de base avec quelque chose \u00e0 faire, en attendant la fin de la temp\u00eate, vous allez s\u00fbrement commencer ressentez de petits sympt\u00f4mes de hauteur. Il faut donc croire qu\u2019il vaut la peine de quitter le confort de son foyer pour pouvoir relever un d\u00e9fi unique, dans une montagne difficile, par la patience et la d\u00e9termination. Si vous n\u2019avez pas la capacit\u00e9 de le faire, vous ne r\u00e9ussirez pas.<\/p>\n\n\n\n<p>Vous devez \u00e9galement vous conna\u00eetre afin de r\u00e9aliser la diff\u00e9rence entre vous pousser et le mal des montagnes, un \u0153d\u00e8me pulmonaire ou c\u00e9r\u00e9bral. Pour la s\u00e9curit\u00e9 de l\u2019\u00e9quipe, le guide en chef d\u00e9terminera qui a besoin d\u2019une journ\u00e9e de repos, qui continue \u00e0 monter ou qui redescend.<\/p>\n\n\n\n<p><em>Veillez \u00e0 pr\u00e9voir au moins un jour de r\u00e9cup\u00e9ration par semaine et \u00e0 bien \u00e9couter votre corps. Prenez la derni\u00e8re semaine pour r\u00e9duire ou r\u00e9duire graduellement l\u2019intensit\u00e9 et le volume de l\u2019entra\u00eenement de sorte que vous soyez bien repos\u00e9, physiquement et psychologiquement, au moment de partir pour votre voyage.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ACONCAGUA CLIMB: ENTRA\u00ceNEMENT DE BASE Escalader l\u2019Aconcagua est, entre autres, une grande satisfaction personnelle et d\u2019\u00e9quipe. Il est certain que si vous voulez profiter de l\u2019exp\u00e9rience de l\u2019alpinisme, tout d\u00e9pend de votre entra\u00eenement pr\u00e9c\u00e9dent. Les chances de succ\u00e8s peuvent \u00eatre grandement am\u00e9lior\u00e9es, ainsi que votre marge de s\u00e9curit\u00e9, afin d\u2019\u00e9viter les maladies et les accidents [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":674,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"_links":{"self":[{"href":"https:\/\/andesport.net\/fr\/wp-json\/wp\/v2\/posts\/1279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andesport.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/andesport.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/andesport.net\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/andesport.net\/fr\/wp-json\/wp\/v2\/comments?post=1279"}],"version-history":[{"count":3,"href":"https:\/\/andesport.net\/fr\/wp-json\/wp\/v2\/posts\/1279\/revisions"}],"predecessor-version":[{"id":3591,"href":"https:\/\/andesport.net\/fr\/wp-json\/wp\/v2\/posts\/1279\/revisions\/3591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/andesport.net\/fr\/wp-json\/wp\/v2\/media\/674"}],"wp:attachment":[{"href":"https:\/\/andesport.net\/fr\/wp-json\/wp\/v2\/media?parent=1279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/andesport.net\/fr\/wp-json\/wp\/v2\/categories?post=1279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/andesport.net\/fr\/wp-json\/wp\/v2\/tags?post=1279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}