{"id":1249,"date":"2023-03-31T13:51:21","date_gmt":"2023-03-31T13:51:21","guid":{"rendered":"https:\/\/www.andesport.com\/?p=1249"},"modified":"2024-05-28T21:04:26","modified_gmt":"2024-05-29T00:04:26","slug":"lascension-de-laconcagua-comment-atteindre-le-sommet","status":"publish","type":"post","link":"https:\/\/andesport.net\/fr\/lascension-de-laconcagua-comment-atteindre-le-sommet\/","title":{"rendered":"L\u2019ASCENSION DE L\u2019ACONCAGUA: COMMENT ATTEINDRE LE SOMMET"},"content":{"rendered":"\n<p>Aconcagua est la destination de randonn\u00e9e la plus spectaculaire d\u2019Argentine. \u00c0 6 962 m\u00e8tres d\u2019altitude, c\u2019est le plus haut sommet de toutes les Am\u00e9riques, ainsi que le plus haut sommet \u00e0 l\u2019ext\u00e9rieur de l\u2019Himalaya. La montagne est situ\u00e9e \u00e0 seulement 112 kilom\u00e8tres de Mendoza, ce qui facilite son acc\u00e8s. Le sommet est une destination d\u2019alpinisme de renomm\u00e9e internationale qui attire des alpinistes de classe mondiale venus du monde entier pour tenter sa chance. La saison d\u2019escalade sur l\u2019Aconcagua dure de d\u00e9cembre \u00e0 mars, bien que la plupart des alpinistes tentent le sommet vers janvier. La condition physique exige une excellente condition physique et la plupart des alpinistes utilisent \u00e9galement un service de guide.<\/p>\n\n\n\n<p><a href=\"http:\/\/www.aconcagua.mendoza.gov.ar\/\" target=\"_blank\" rel=\"noopener\">Le parc provincial Aconcagua&nbsp;<\/a>offre de superbes randonn\u00e9es d\u2019une journ\u00e9e et des randonn\u00e9es de plusieurs jours, le tout offrant une vue imprenable sur la montagne. Pour les randonn\u00e9es de plusieurs jours, les randonneurs peuvent choisir entre la vall\u00e9e de Horcones et la vall\u00e9e de Vacas. Le service du parc d\u00e9livre des permis pour les treks courts (trois jours) ou longs (sept jours), tant que les treks restent en dessous de 4 300 m. En raison de la popularit\u00e9 de l\u2019Aconcagua, le service des parcs est en mesure de facturer des prix beaucoup plus \u00e9lev\u00e9s pour ces permis.<\/p>\n\n\n\n<p>Si vous souhaitez voir la montagne gratuitement, une petite boucle que vous pourrez faire en dehors du centre des visiteurs vous m\u00e8nera \u00e0 quelques lacs plus petits et vous offrira de superbes vues sur les montagnes. Bien que ce ne soit pas l\u2019option de randonn\u00e9e la plus \u00e9conomique, Aconcagua est une destination incontournable pour les randonneurs exp\u00e9riment\u00e9s en Argentine.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aconcagua est la destination de randonn\u00e9e la plus spectaculaire d\u2019Argentine. \u00c0 6 962 m\u00e8tres d\u2019altitude, c\u2019est le plus haut sommet de toutes les Am\u00e9riques, ainsi que le plus haut sommet \u00e0 l\u2019ext\u00e9rieur de l\u2019Himalaya. La montagne est situ\u00e9e \u00e0 seulement 112 kilom\u00e8tres de Mendoza, ce qui facilite son acc\u00e8s. Le sommet est une destination d\u2019alpinisme [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":612,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"_links":{"self":[{"href":"https:\/\/andesport.net\/fr\/wp-json\/wp\/v2\/posts\/1249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andesport.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/andesport.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/andesport.net\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/andesport.net\/fr\/wp-json\/wp\/v2\/comments?post=1249"}],"version-history":[{"count":1,"href":"https:\/\/andesport.net\/fr\/wp-json\/wp\/v2\/posts\/1249\/revisions"}],"predecessor-version":[{"id":3520,"href":"https:\/\/andesport.net\/fr\/wp-json\/wp\/v2\/posts\/1249\/revisions\/3520"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/andesport.net\/fr\/wp-json\/wp\/v2\/media\/612"}],"wp:attachment":[{"href":"https:\/\/andesport.net\/fr\/wp-json\/wp\/v2\/media?parent=1249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/andesport.net\/fr\/wp-json\/wp\/v2\/categories?post=1249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/andesport.net\/fr\/wp-json\/wp\/v2\/tags?post=1249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}